{"id":245,"date":"2025-12-07T05:35:23","date_gmt":"2025-12-07T05:35:23","guid":{"rendered":"https:\/\/erendogu.com\/?page_id=245"},"modified":"2025-12-07T21:50:13","modified_gmt":"2025-12-07T21:50:13","slug":"sertifikalarim","status":"publish","type":"page","link":"https:\/\/erendogu.com\/tr\/sertifikalarim\/","title":{"rendered":"Sertifikalar\u0131m"},"content":{"rendered":"<h2 class=\"wp-block-heading\">BTK Akademiden<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"267\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-1024x724.webp\" alt=\"\" class=\"wp-image-267\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ag_Temelleri_Sertifika_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"270\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-270\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgi_Teknolojilerine_Giris_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"271\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-271\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/DoS___DDos_Saldirilari_ve_Koruma_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"272\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-272\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Egitimde_Oyunlastirma_ve_Web_2.0_Araclari_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"262\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-1024x724.webp\" alt=\"\" class=\"wp-image-262\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Etkili_Iletisim_Stratejileri_Sertifika_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"268\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-1024x724.png\" alt=\"\" class=\"wp-image-268\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-1024x724.png 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-300x212.png 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-768x543.png 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-1536x1086.png 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Ikna_Becerileri_Sertifika_1-2048x1448.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"273\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-273\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Isletim_Sistemlerine_Giris_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"274\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-274\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyerde_Hedef_Belirleme_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"275\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-275\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kariyeri_Tehdit_Eden_Yaklasimlar_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"276\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-276\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/LinkedInde_Etkili_Profil_Olusturma_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"277\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-277\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Pardus_Arayuz_Kullanimi_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"278\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-278\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Proje_Yonetim_Temelleri__Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"279\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-279\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Siber_Guvenlikte_Linux_Isletim_Sistemleri_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"280\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-280\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_10_Isletim_Sistemi_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"281\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-1024x724.webp\" alt=\"\" class=\"wp-image-281\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Windows_11_Isletim_Sistemi_Sertifika_1-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sorbilden<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"792\" data-id=\"288\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-1024x792.webp\" alt=\"\" class=\"wp-image-288\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-1024x792.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-768x594.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-1536x1187.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Etkili-Iletisim-Egitimi-certificate_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"792\" data-id=\"292\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-1024x792.webp\" alt=\"\" class=\"wp-image-292\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-1024x792.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-768x594.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-1536x1187.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Sifirdan-Ileriye-ChatGPT-Egitimi-certificate_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"792\" data-id=\"289\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-1024x792.webp\" alt=\"\" class=\"wp-image-289\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-1024x792.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-768x594.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-1536x1187.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Youtube-Egitimi-certificate_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"792\" data-id=\"291\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-1024x792.webp\" alt=\"\" class=\"wp-image-291\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-1024x792.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-768x594.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-1536x1187.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Facebook-Reklam-Egitimi-certificate_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"792\" data-id=\"290\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-1024x792.webp\" alt=\"\" class=\"wp-image-290\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-1024x792.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-768x594.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-1536x1187.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Eren-Dogu-Adan-Zye-Instagram-Egitimi-certificate_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Bilge\u0130\u015f<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"296\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-1024x724.webp\" alt=\"\" class=\"wp-image-296\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-1024x724.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-300x212.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-768x543.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-1536x1086.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Sizma_Testine_Giris-Sertifika_448343_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" data-id=\"299\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-1024x793.webp\" alt=\"\" class=\"wp-image-299\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-1024x793.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-768x595.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-1536x1190.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Kisisel_Stres_Yonetimi-Sertifika_448626_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" data-id=\"301\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-1024x793.webp\" alt=\"\" class=\"wp-image-301\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-1024x793.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-768x595.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-1536x1190.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Internette_Guvenliginizi_Arttirin-Sertifika_448246_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" data-id=\"298\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-1024x793.webp\" alt=\"\" class=\"wp-image-298\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-1024x793.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-768x595.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-1536x1190.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Slaytlar_Ile_Etkili_Sunum_Hazirlama-Sertifika_456509-1_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" data-id=\"300\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-1024x793.webp\" alt=\"\" class=\"wp-image-300\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-1024x793.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-768x595.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-1536x1190.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Google_Drive_ile_Bulut_Teknolojisine_Giris-Sertifika_448196_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" data-id=\"297\" src=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-1024x793.webp\" alt=\"\" class=\"wp-image-297\" srcset=\"https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-1024x793.webp 1024w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-300x232.webp 300w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-768x595.webp 768w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-1536x1190.webp 1536w, https:\/\/erendogu.com\/wp-content\/uploads\/2025\/12\/Bilgisayardaki_Dosyalarin_Guvenligi_ve_Veri_Kurtarma-Sertifika_448278_1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>BTK Akademiden Sorbilden Bilge\u0130\u015f<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_gspb_post_css":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"wpai_generated_summary":"","footnotes":""},"class_list":["post-245","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/pages\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":31,"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/pages\/245\/revisions"}],"predecessor-version":[{"id":391,"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/pages\/245\/revisions\/391"}],"wp:attachment":[{"href":"https:\/\/erendogu.com\/tr\/wp-json\/wp\/v2\/media?parent=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}